{"id":5104,"date":"2022-11-07T16:26:11","date_gmt":"2022-11-07T16:26:11","guid":{"rendered":"https:\/\/www.science-metrix.com\/?p=5104"},"modified":"2022-11-07T16:31:04","modified_gmt":"2022-11-07T16:31:04","slug":"assessing-the-impact-of-uk-investment-in-the-european-space-agency","status":"publish","type":"post","link":"https:\/\/www.science-metrix.com\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/","title":{"rendered":"\u00c9valuer l\u2019impact des investissements du Royaume-Uni dans l\u2019Agence spatiale europ\u00e9enne"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5104\" class=\"elementor elementor-5104\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4765e579 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4765e579\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c40f988\" data-id=\"2c40f988\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-744f2679 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"744f2679\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5db0cb5d elementor-widget elementor-widget-heading\" data-id=\"5db0cb5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9valuer l\u2019impact des investissements du Royaume-Uni dans l\u2019Agence spatiale europ\u00e9enne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c0443 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c0443\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-636e8815\" data-id=\"636e8815\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e4400e9 elementor-widget elementor-widget-text-editor\" data-id=\"3e4400e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>novembre 2022<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48ee648b elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48ee648b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-53890832\" data-id=\"53890832\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a6e4204 elementor-widget elementor-widget-text-editor\" data-id=\"2a6e4204\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019Agence spatiale du Royaume Uni a mandat\u00e9 un consortium, dont Science-Metrix fait partie, pour la conception, le d\u00e9veloppement et la mise en \u0153uvre d\u2019un programme de suivi et d\u2019\u00e9valuation des effets de ses investissements dans l\u2019Agence spatiale europ\u00e9enne (ESA).\u00a0<\/p><p>Pr\u00e8s du trois quarts du budget du Royaume-Uni en mati\u00e8re spatiale, repr\u00e9sentant une somme de 420 \u00e0 450 millions d\u2019Euro, est allou\u00e9 au programme de l\u2019ESA. L\u2019objectif de ce projet \u00e9tait d\u2019estimer les b\u00e9n\u00e9fices des investissement pr\u00e9c\u00e9dents et d\u2019\u00e9tablir un cadre d\u2019\u00e9valuation pour mesurer les futurs impacts.<\/p><p>La contribution de Science-Metrix portait principalement sur la portion bibliographique et technom\u00e9trique du projet :<\/p><ul><li>Pr\u00e9parer une enveloppe de publications capturant les travaux faits en science spatiale \u00e0 l\u2019aide de mots cl\u00e9s sp\u00e9cifiques et enrichis par les th\u00e8mes propos\u00e9s par SciVal;<\/li><li>Identifier les publications li\u00e9es \u00e0 un financement de l\u2019ESA, soit directement via les donn\u00e9es des missions spatiales, ou \u00e0 l\u2019aide des auteurs et d\u2019une cartographie de leurs publications aux champs d\u2019activit\u00e9s de l\u2019agence;<\/li><li>Construire une base de donn\u00e9es de brevets associ\u00e9s \u00e0 la science spatiale et aux technologies connexes;<\/li><li>Produire des indicateurs bibliom\u00e9triques et technom\u00e9triques \u00e0 l\u2019\u00e9chelle nationale et institutionnelle pour le domaine spatial dans son ensemble, en utilisant l\u2019enveloppe de publications sp\u00e9cifiques \u00e0 la science spatiale, et pour les publications financ\u00e9es par l\u2019ESA, afin de comparer l\u2019impact de l\u2019agence \u00e0 l\u2019impact du domaine.<\/li><\/ul><div>\u00a0<\/div><p><span style=\"color: var( --e-global-color-text ); letter-spacing: 0px;\">Le rapport r\u00e9dig\u00e9 par Technopolis a r\u00e9cemment \u00e9t\u00e9 publi\u00e9 en ligne. Les statistiques produites par Science-Metrix se retrouvent aux chapitres 4 et 5.<\/span><\/p><p><span style=\"color: var( --e-global-color-text ); letter-spacing: 0px;\">Pour lire le rapport :<\/span><\/p><p><a href=\"https:\/\/www.technopolis-group.com\/wp-content\/uploads\/2022\/10\/3617-Impact-Evaluation-Report_PART-A_220427_FINAL-1.pdf\" target=\"_blank\" rel=\"noopener\">Section A (anglais)<\/a><\/p><p><a href=\"https:\/\/www.technopolis-group.com\/wp-content\/uploads\/2022\/10\/3617-Impact-Evaluation-Report_PART-B_220808_FINAL.pdf\" target=\"_blank\" rel=\"noopener\">Section B (anglais)<\/a><\/p><p><a href=\"https:\/\/www.technopolis-group.com\/wp-content\/uploads\/2022\/10\/3617-Impact-Evaluation-Report_Technical-Annex_220427_FINAL-1.pdf\" target=\"_blank\" rel=\"noopener\">Annexe technique (anglais)<\/a><\/p><p><span style=\"color: var( --e-global-color-text ); letter-spacing: 0px;\">Image : iStock<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-482b9ace\" data-id=\"482b9ace\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47c55182 elementor-widget elementor-widget-image\" data-id=\"47c55182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"499\" src=\"https:\/\/mail.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654-1024x639.jpg\" class=\"attachment-large size-large wp-image-5110\" alt=\"rocket blasting into space\" srcset=\"https:\/\/mail.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654-1024x639.jpg 1024w, https:\/\/mail.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654-300x187.jpg 300w, https:\/\/mail.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654-768x479.jpg 768w, https:\/\/mail.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654-18x12.jpg 18w, https:\/\/mail.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg 1297w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Assessing the impact of UK investment in the European Space Agency November 2022 The UK Space Agency commissioned a consortium, of which Science-Metrix was part, to design, develop, and implement a monitoring and evaluation programme for the UK Space Agency\u2019s investment in the European Space Agency (ESA).&nbsp; The UK allocates approximately three-quarters of its space [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[14,73,25,75,76,74],"class_list":["post-5104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bibliometrics","tag-european-space-agency","tag-indicator-development","tag-monitoring-and-evaluation","tag-technometrics","tag-uk-space-agency"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assessing the impact of UK investment in the European Space Agency - Science-Metrix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assessing the impact of UK investment in the European Space Agency - Science-Metrix\" \/>\n<meta property=\"og:description\" content=\"Assessing the impact of UK investment in the European Space Agency November 2022 The UK Space Agency commissioned a consortium, of which Science-Metrix was part, to design, develop, and implement a monitoring and evaluation programme for the UK Space Agency\u2019s investment in the European Space Agency (ESA).&nbsp; The UK allocates approximately three-quarters of its space [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/\" \/>\n<meta property=\"og:site_name\" content=\"Science-Metrix\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-07T16:26:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-07T16:31:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1297\" \/>\n\t<meta property=\"og:image:height\" content=\"809\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisabeth Browning\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisabeth Browning\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/\"},\"author\":{\"name\":\"Elisabeth Browning\",\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#\\\/schema\\\/person\\\/247feab70566ca20d06e6e83996d3e0b\"},\"headline\":\"Assessing the impact of UK investment in the European Space Agency\",\"datePublished\":\"2022-11-07T16:26:11+00:00\",\"dateModified\":\"2022-11-07T16:31:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/\"},\"wordCount\":260,\"publisher\":{\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.science-metrix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/iStock-1346401654.jpg\",\"keywords\":[\"bibliometrics\",\"European Space Agency\",\"indicator development\",\"monitoring and evaluation\",\"technometrics\",\"UK Space Agency\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/\",\"url\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/\",\"name\":\"Assessing the impact of UK investment in the European Space Agency - Science-Metrix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.science-metrix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/iStock-1346401654.jpg\",\"datePublished\":\"2022-11-07T16:26:11+00:00\",\"dateModified\":\"2022-11-07T16:31:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.science-metrix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/iStock-1346401654.jpg\",\"contentUrl\":\"https:\\\/\\\/www.science-metrix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/iStock-1346401654.jpg\",\"width\":1297,\"height\":809,\"caption\":\"Space shuttle rocket launch in the clouds with stars to outer space. Space on background. Sky and clouds. Spaceship flight. Elements of this image furnished by NASA (url: https:\\\/\\\/www.nasa.gov\\\/sites\\\/default\\\/files\\\/styles\\\/full_width_feature\\\/public\\\/images\\\/164234main_image_feature_713_ys_full.jpg)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wp135259.wpdns.ca\\\/fr\\\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/science-metrix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assessing the impact of UK investment in the European Space Agency\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#website\",\"url\":\"https:\\\/\\\/science-metrix.com\\\/\",\"name\":\"Science-Metrix\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/science-metrix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#organization\",\"name\":\"Science-Metrix\",\"url\":\"https:\\\/\\\/science-metrix.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.science-metrix.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo_SM_website.png\",\"contentUrl\":\"https:\\\/\\\/www.science-metrix.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo_SM_website.png\",\"width\":1493,\"height\":199,\"caption\":\"Science-Metrix\"},\"image\":{\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/science-metrix.com\\\/#\\\/schema\\\/person\\\/247feab70566ca20d06e6e83996d3e0b\",\"name\":\"Elisabeth Browning\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ce3ed456b188d59b5a1e2cba2b96eff6e49256083362bb8c81f8381d94f177?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ce3ed456b188d59b5a1e2cba2b96eff6e49256083362bb8c81f8381d94f177?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ce3ed456b188d59b5a1e2cba2b96eff6e49256083362bb8c81f8381d94f177?s=96&d=mm&r=g\",\"caption\":\"Elisabeth Browning\"},\"url\":\"https:\\\/\\\/www.science-metrix.com\\\/fr\\\/author\\\/elisabeth\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assessing the impact of UK investment in the European Space Agency - Science-Metrix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/","og_locale":"fr_CA","og_type":"article","og_title":"Assessing the impact of UK investment in the European Space Agency - Science-Metrix","og_description":"Assessing the impact of UK investment in the European Space Agency November 2022 The UK Space Agency commissioned a consortium, of which Science-Metrix was part, to design, develop, and implement a monitoring and evaluation programme for the UK Space Agency\u2019s investment in the European Space Agency (ESA).&nbsp; The UK allocates approximately three-quarters of its space [&hellip;]","og_url":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/","og_site_name":"Science-Metrix","article_published_time":"2022-11-07T16:26:11+00:00","article_modified_time":"2022-11-07T16:31:04+00:00","og_image":[{"width":1297,"height":809,"url":"https:\/\/www.wp135259.wpdns.ca\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg","type":"image\/jpeg"}],"author":"Elisabeth Browning","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Elisabeth Browning","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/#article","isPartOf":{"@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/"},"author":{"name":"Elisabeth Browning","@id":"https:\/\/science-metrix.com\/#\/schema\/person\/247feab70566ca20d06e6e83996d3e0b"},"headline":"Assessing the impact of UK investment in the European Space Agency","datePublished":"2022-11-07T16:26:11+00:00","dateModified":"2022-11-07T16:31:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/"},"wordCount":260,"publisher":{"@id":"https:\/\/science-metrix.com\/#organization"},"image":{"@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/#primaryimage"},"thumbnailUrl":"https:\/\/www.science-metrix.com\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg","keywords":["bibliometrics","European Space Agency","indicator development","monitoring and evaluation","technometrics","UK Space Agency"],"articleSection":["News"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/","url":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/","name":"Assessing the impact of UK investment in the European Space Agency - Science-Metrix","isPartOf":{"@id":"https:\/\/science-metrix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/#primaryimage"},"image":{"@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/#primaryimage"},"thumbnailUrl":"https:\/\/www.science-metrix.com\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg","datePublished":"2022-11-07T16:26:11+00:00","dateModified":"2022-11-07T16:31:04+00:00","breadcrumb":{"@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/#primaryimage","url":"https:\/\/www.science-metrix.com\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg","contentUrl":"https:\/\/www.science-metrix.com\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg","width":1297,"height":809,"caption":"Space shuttle rocket launch in the clouds with stars to outer space. Space on background. Sky and clouds. Spaceship flight. Elements of this image furnished by NASA (url: https:\/\/www.nasa.gov\/sites\/default\/files\/styles\/full_width_feature\/public\/images\/164234main_image_feature_713_ys_full.jpg)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wp135259.wpdns.ca\/fr\/assessing-the-impact-of-uk-investment-in-the-european-space-agency\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/science-metrix.com\/"},{"@type":"ListItem","position":2,"name":"Assessing the impact of UK investment in the European Space Agency"}]},{"@type":"WebSite","@id":"https:\/\/science-metrix.com\/#website","url":"https:\/\/science-metrix.com\/","name":"Science-Metrix","description":"","publisher":{"@id":"https:\/\/science-metrix.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/science-metrix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/science-metrix.com\/#organization","name":"Science-Metrix","url":"https:\/\/science-metrix.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/science-metrix.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.science-metrix.com\/wp-content\/uploads\/2021\/10\/Logo_SM_website.png","contentUrl":"https:\/\/www.science-metrix.com\/wp-content\/uploads\/2021\/10\/Logo_SM_website.png","width":1493,"height":199,"caption":"Science-Metrix"},"image":{"@id":"https:\/\/science-metrix.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/science-metrix.com\/#\/schema\/person\/247feab70566ca20d06e6e83996d3e0b","name":"Elisabeth Browning","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/b5ce3ed456b188d59b5a1e2cba2b96eff6e49256083362bb8c81f8381d94f177?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5ce3ed456b188d59b5a1e2cba2b96eff6e49256083362bb8c81f8381d94f177?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5ce3ed456b188d59b5a1e2cba2b96eff6e49256083362bb8c81f8381d94f177?s=96&d=mm&r=g","caption":"Elisabeth Browning"},"url":"https:\/\/www.science-metrix.com\/fr\/author\/elisabeth\/"}]}},"jetpack_featured_media_url":"https:\/\/www.science-metrix.com\/wp-content\/uploads\/2022\/11\/iStock-1346401654.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/posts\/5104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/comments?post=5104"}],"version-history":[{"count":25,"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/posts\/5104\/revisions"}],"predecessor-version":[{"id":5132,"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/posts\/5104\/revisions\/5132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/media\/5110"}],"wp:attachment":[{"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/media?parent=5104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/categories?post=5104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.science-metrix.com\/fr\/wp-json\/wp\/v2\/tags?post=5104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}